{"id":2751,"date":"2024-02-13T15:27:59","date_gmt":"2024-02-13T14:27:59","guid":{"rendered":"https:\/\/www.corlidogroup.com\/ubicaciones\/"},"modified":"2026-02-02T16:43:08","modified_gmt":"2026-02-02T15:43:08","slug":"ubicaciones","status":"publish","type":"page","link":"https:\/\/www.corlidogroup.com\/es\/ubicaciones\/","title":{"rendered":"Ubicaciones"},"content":{"rendered":"\n<section class=\"pane pane--quaternary\">\n    <div class=\"container\">\n                    <div class=\"row mb-6 mb-lg-12\">\n                <div class=\"col-12\">\n                                        <div class=\"pane__text\">\n                        <h2 style=\"text-align: center\">Corlido en todo el mundo<\/h2>\n<p style=\"text-align: center\">Nuestra presencia global, vea d\u00f3nde se encuentran nuestras oficinas.<\/p>\n                                                \n                    <\/div>\n                <\/div>\n            <\/div>\n                <div class=\"row justify-content-center\">\n            <div class=\"col-12 col-lg-11 col-xl-10\">\n                <div class=\"map\">\n                    <ul class=\"list\">                            <li class=\"list__item\" style=\"top:47%;left:19%;background-color:#FF7F00;\" data-target=\"marker_1\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_1\"><\/button>\n                                <div class=\"card card--location\">\n                                    <img decoding=\"async\" class=\"card-img-top\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/Pand-Amerika-450x360.jpg\" alt=\"\">                                    <div class=\"card-body\">\n                                        <h3 class=\"card-title\">Estados Unidos<\/h3>\n                                                                                    <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <span>+1(713)382-0121<\/span>\n                                            <\/p>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                                                        <li class=\"list__item\" style=\"top:29%;left:45%;background-color:#FF7F00;\" data-target=\"marker_2\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_2\"><\/button>\n                                <div class=\"card card--location\">\n                                    <img decoding=\"async\" class=\"card-img-top\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/11\/Ontwerp-zonder-titel-1-450x360.png\" alt=\"\">                                    <div class=\"card-body\">\n                                        <h3 class=\"card-title\">Reino Unido<\/h3>\n                                                                                    <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <span>+44 1902 287 216<\/span>\n                                            <\/p>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                                                        <li class=\"list__item\" style=\"top:48%;left:60%;background-color:#FF7F00;\" data-target=\"marker_3\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_3\"><\/button>\n                                <div class=\"card card--location\">\n                                    <img decoding=\"async\" class=\"card-img-top\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Pand-Dubai-2-450x360.jpg\" alt=\"\">                                    <div class=\"card-body\">\n                                        <h3 class=\"card-title\">EAU<\/h3>\n                                                                                    <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <span>+971 566 445 946<\/span>\n                                            <\/p>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                                                        <li class=\"list__item\" style=\"top:22%;left:51.5%;background-color:#5bc1f3;\" data-target=\"marker_4\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_4\"><\/button>\n                                <div class=\"card card--location\">\n                                                                        <div class=\"card-body\">\n                                        <h3 class=\"card-title\">Suecia<\/h3>\n                                                                                    <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <span>+31 (0) 88 \u2013 536 00 00<\/span>\n                                            <\/p>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                                                        <li class=\"list__item\" style=\"top:42%;left:81%;background-color:#0e2d46;\" data-target=\"marker_5\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_5\"><\/button>\n                                <div class=\"card card--location\">\n                                                                        <div class=\"card-body\">\n                                        <h3 class=\"card-title\">Corea del Sur<\/h3>\n                                                                                    <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <span>+ 8210 3747 5524<\/span>\n                                            <\/p>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                                                        <li class=\"list__item\" style=\"top:45%;left:58%;background-color:#FF7F00;\" data-target=\"marker_6\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_6\"><\/button>\n                                <div class=\"card card--location\">\n                                    <img decoding=\"async\" class=\"card-img-top\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/1-450x360.jpg\" alt=\"\">                                    <div class=\"card-body\">\n                                        <h3 class=\"card-title\">Arabia Saudita<\/h3>\n                                                                                    <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <span>+966 (0) 13 344 4599<\/span>\n                                            <\/p>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                                                        <li class=\"list__item\" style=\"top:38%;left:56%;background-color:#5bc1f3;\" data-target=\"marker_7\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_7\"><\/button>\n                                <div class=\"card card--location\">\n                                                                        <div class=\"card-body\">\n                                        <h3 class=\"card-title\">Ruman\u00eda<\/h3>\n                                                                                    <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <span>+31 (0) 88 \u2013 536 00 00<\/span>\n                                            <\/p>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                                                        <li class=\"list__item\" style=\"top:31%;left:53%;background-color:#FF7F00;\" data-target=\"marker_8\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_8\"><\/button>\n                                <div class=\"card card--location\">\n                                    <img decoding=\"async\" class=\"card-img-top\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Pand-Polen-450x360.jpg\" alt=\"\">                                    <div class=\"card-body\">\n                                        <h3 class=\"card-title\">Polonia<\/h3>\n                                                                                    <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <span>+48 12 346 50 37  <\/span>\n                                            <\/p>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                                                        <li class=\"list__item\" style=\"top:34%;left:48.5%;background-color:#5bc1f3;\" data-target=\"marker_9\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_9\"><\/button>\n                                <div class=\"card card--location\">\n                                                                        <div class=\"card-body\">\n                                        <h3 class=\"card-title\">Luxemburgo<\/h3>\n                                                                                    <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <span>+31 (0) 88 \u2013 536 00 00<\/span>\n                                            <\/p>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                                                        <li class=\"list__item\" style=\"top:35%;left:60%;background-color:#FF7F00;\" data-target=\"marker_10\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_10\"><\/button>\n                                <div class=\"card card--location\">\n                                    <img decoding=\"async\" class=\"card-img-top\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Pand-Kazakhstan-450x360.jpg\" alt=\"\">                                    <div class=\"card-body\">\n                                        <h3 class=\"card-title\">Kazajist\u00e1n<\/h3>\n                                                                                    <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <span>+7 495 51 40 394<\/span>\n                                            <\/p>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                                                        <li class=\"list__item\" style=\"top:37%;left:50%;background-color:#0e2d46;\" data-target=\"marker_11\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_11\"><\/button>\n                                <div class=\"card card--location\">\n                                                                        <div class=\"card-body\">\n                                        <h3 class=\"card-title\">Italia<\/h3>\n                                                                                    <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <span>+31 (0) 88 536 00 33  <\/span>\n                                            <\/p>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                                                        <li class=\"list__item\" style=\"top:58%;left:46%;background-color:#0e2d46;\" data-target=\"marker_12\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_12\"><\/button>\n                                <div class=\"card card--location\">\n                                                                        <div class=\"card-body\">\n                                        <h3 class=\"card-title\">Ghana<\/h3>\n                                                                                    <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <span>+233 302 778 432<\/span>\n                                            <\/p>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                                                        <li class=\"list__item\" style=\"top:32%;left:50%;background-color:#FF7F00;\" data-target=\"marker_13\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_13\"><\/button>\n                                <div class=\"card card--location\">\n                                    <img decoding=\"async\" class=\"card-img-top\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Pand-Duitsland-450x360.jpeg\" alt=\"\">                                    <div class=\"card-body\">\n                                        <h3 class=\"card-title\">Alemania<\/h3>\n                                                                                    <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <span>  +49 (0)5921 857 970<\/span>\n                                            <\/p>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                                                        <li class=\"list__item\" style=\"top:34%;left:46%;background-color:#5bc1f3;\" data-target=\"marker_14\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_14\"><\/button>\n                                <div class=\"card card--location\">\n                                                                        <div class=\"card-body\">\n                                        <h3 class=\"card-title\">Francia<\/h3>\n                                                                                    <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <span>+31 (0) 88 \u2013 536 00 00<\/span>\n                                            <\/p>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                                                        <li class=\"list__item\" style=\"top:61%;left:49%;background-color:#0e2d46;\" data-target=\"marker_15\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_15\"><\/button>\n                                <div class=\"card card--location\">\n                                                                        <div class=\"card-body\">\n                                        <h3 class=\"card-title\">Guinea Ecuatorial<\/h3>\n                                                                                    <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <span>+240 222 047 187<\/span>\n                                            <\/p>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                                                        <li class=\"list__item\" style=\"top:28%;left:49%;background-color:#5bc1f3;\" data-target=\"marker_16\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_16\"><\/button>\n                                <div class=\"card card--location\">\n                                                                        <div class=\"card-body\">\n                                        <h3 class=\"card-title\">Dinamarca<\/h3>\n                                                                                    <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <span>+31 (0) 88 \u2013 536 00 00<\/span>\n                                            <\/p>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                                                        <li class=\"list__item\" style=\"top:33.5%;left:52%;background-color:#5bc1f3;\" data-target=\"marker_17\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_17\"><\/button>\n                                <div class=\"card card--location\">\n                                                                        <div class=\"card-body\">\n                                        <h3 class=\"card-title\">Rep\u00fablica Checa<\/h3>\n                                                                                    <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <span>+31 (0) 88 \u2013 536 00 00<\/span>\n                                            <\/p>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                                                        <li class=\"list__item\" style=\"top:58.5%;left:25.5%;background-color:#0e2d46;\" data-target=\"marker_18\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_18\"><\/button>\n                                <div class=\"card card--location\">\n                                                                        <div class=\"card-body\">\n                                        <h3 class=\"card-title\">Colombia<\/h3>\n                                                                                    <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <span>+57 320 4668460<\/span>\n                                            <\/p>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                                                        <li class=\"list__item\" style=\"top:38%;left:78%;background-color:#0e2d46;\" data-target=\"marker_19\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_19\"><\/button>\n                                <div class=\"card card--location\">\n                                                                        <div class=\"card-body\">\n                                        <h3 class=\"card-title\">China<\/h3>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                                                        <li class=\"list__item\" style=\"top:51%;left:51%;background-color:#0e2d46;\" data-target=\"marker_20\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_20\"><\/button>\n                                <div class=\"card card--location\">\n                                                                        <div class=\"card-body\">\n                                        <h3 class=\"card-title\">Chad<\/h3>\n                                                                                    <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <span>+235 63 614 125<\/span>\n                                            <\/p>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                                                        <li class=\"list__item\" style=\"top:58%;left:48%;background-color:#0e2d46;\" data-target=\"marker_21\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_21\"><\/button>\n                                <div class=\"card card--location\">\n                                                                        <div class=\"card-body\">\n                                        <h3 class=\"card-title\">Camer\u00fan<\/h3>\n                                                                                    <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <span>+237 233 472 051<\/span>\n                                            <\/p>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                                                        <li class=\"list__item\" style=\"top:62%;left:78%;background-color:#0e2d46;\" data-target=\"marker_22\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_22\"><\/button>\n                                <div class=\"card card--location\">\n                                                                        <div class=\"card-body\">\n                                        <h3 class=\"card-title\">Brunei<\/h3>\n                                                                                    <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <span>+673 717 50 61<\/span>\n                                            <\/p>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                                                        <li class=\"list__item\" style=\"top:33%;left:47.5%;background-color:#5bc1f3;\" data-target=\"marker_23\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_23\"><\/button>\n                                <div class=\"card card--location\">\n                                                                        <div class=\"card-body\">\n                                        <h3 class=\"card-title\">B\u00e9lgica<\/h3>\n                                                                                    <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <span>+31 (0) 88 \u2013 536 00 00<\/span>\n                                            <\/p>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                                                        <li class=\"list__item\" style=\"top:34%;left:49%;background-color:#5bc1f3;\" data-target=\"marker_24\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_24\"><\/button>\n                                <div class=\"card card--location\">\n                                                                        <div class=\"card-body\">\n                                        <h3 class=\"card-title\">Austria<\/h3>\n                                                                                    <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <span>+49 (0)5921 857 970<\/span>\n                                            <\/p>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                                                        <li class=\"list__item\" style=\"top:68%;left:50.5%;background-color:#0e2d46;\" data-target=\"marker_25\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_25\"><\/button>\n                                <div class=\"card card--location\">\n                                                                        <div class=\"card-body\">\n                                        <h3 class=\"card-title\">Angola<\/h3>\n                                                                                    <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <span>+244 940 732 211<\/span>\n                                            <\/p>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                                                        <li class=\"list__item\" style=\"top:31%;left:48%;background-color:#FF7F00;\" data-target=\"marker_26\">\n                                <button type=\"button\" class=\"btn\" data-toggle=\"marker_26\"><\/button>\n                                <div class=\"card card--location\">\n                                    <img decoding=\"async\" class=\"card-img-top\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/CORLIDO-JULI-2016-07.jpeg\" alt=\"\">                                    <div class=\"card-body\">\n                                        <h3 class=\"card-title\">Pa\u00edses Bajos (sede central)<\/h3>\n                                                                                    <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <span>+31 (0) 88 \u2013 536 00 00<\/span>\n                                            <\/p>\n                                                                            <\/div>\n                                <\/div>\n                            <\/li>\n                            <\/ul>                    <img loading=\"lazy\" decoding=\"async\" class=\"map__image img-fluid\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/corlido-map.svg\" alt=\"All Corlido locations\" width=\"1190\" height=\"595\" \/>\n                <\/div>\n                <ul class=\"list list--legenda mt-6 mt-lg-10\">\n                                                <li class=\"list__item\">\n                                                                    <span class=\"list__dot\" style=\"background-color:#0e2d46;\"><\/span>\n                                                                <span>Representante<\/span>\n                            <\/li>\n                                                    <li class=\"list__item\">\n                                                                    <span class=\"list__dot\" style=\"background-color:#5bc1f3;\"><\/span>\n                                                                <span>Registro del IVA<\/span>\n                            <\/li>\n                                                    <li class=\"list__item\">\n                                                                    <span class=\"list__dot\" style=\"background-color:#FF7F00;\"><\/span>\n                                                                <span>Oficina<\/span>\n                            <\/li>\n                                        <\/ul>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n<section class=\"pane pane--quaternary\">\n    <div class=\"container\">\n        <div class=\"row g-4 g-lg-5 g-xl-6\">\n                                <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/netherlands-150x150.jpg\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" \/>                                <span class=\"card__dot\" style=\"background-color:#FF7F00;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2730\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2730\">\n                                <h3 class=\"card-title mb-0 pe-4\">Pa\u00edses Bajos (sede central)<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2730\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>James Cookstraat 53<br \/>\n7825 AX Emmen<br \/>\n<br \/>\n<br \/>\nJP Bos <\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+31 (0) 88 \u2013 536 00 00\">+31 (0) 88 \u2013 536 00 00<\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/angola-150x150.png\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/angola-150x150.png 150w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/angola-300x300.png 300w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/angola-70x70.png 70w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/angola.png 500w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>                                <span class=\"card__dot\" style=\"background-color:#0e2d46;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2729\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2729\">\n                                <h3 class=\"card-title mb-0 pe-4\">Angola<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2729\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>Talatona.B.Patriota<br \/>\nSN. Largo Dr. Agostinho<br \/>\nNeto. Luanda  <br \/>\n<br \/>\nBakci Soares<\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+244 940 732 211\">+244 940 732 211<\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Austria-150x150.png\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Austria-150x150.png 150w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Austria-70x70.png 70w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Austria.png 225w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>                                <span class=\"card__dot\" style=\"background-color:#5bc1f3;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2731\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2731\">\n                                <h3 class=\"card-title mb-0 pe-4\">Austria<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2731\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>Stubenring 24<br \/>\n1010 Wien<br \/>\n<br \/>\n<br \/>\nHerbert Dirkes<\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+49 (0)5921 857 970\">+49 (0)5921 857 970<\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/Belgie-150x150.png\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" \/>                                <span class=\"card__dot\" style=\"background-color:#5bc1f3;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2732\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2732\">\n                                <h3 class=\"card-title mb-0 pe-4\">B\u00e9lgica<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2732\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>Namenstraat 9<br \/>\n2000 Antwerpen<\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+31 (0) 88 \u2013 536 00 00\">+31 (0) 88 \u2013 536 00 00<\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/Brunei-150x150.png\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/Brunei-150x150.png 150w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/Brunei-70x70.png 70w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/Brunei.png 250w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>                                <span class=\"card__dot\" style=\"background-color:#0e2d46;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2733\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2733\">\n                                <h3 class=\"card-title mb-0 pe-4\">Brunei<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2733\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>8th Floor PGGMB Building<br \/>\nJalan Kianggeh.<br \/>\nBandar Seri Begawan BS8111<br \/>\n<br \/>\nPatimah Yusop<\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+673 717 50 61\">+673 717 50 61<\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Cameroon-150x150.png\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Cameroon-150x150.png 150w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Cameroon-300x300.png 300w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Cameroon-70x70.png 70w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Cameroon.png 512w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>                                <span class=\"card__dot\" style=\"background-color:#0e2d46;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2734\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2734\">\n                                <h3 class=\"card-title mb-0 pe-4\">Camer\u00fan<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2734\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>Nkotto \u2013Bonamoussadi<br \/>\nBP4217 Douala<br \/>\n<br \/>\n<br \/>\nAboubakari Yaya<\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+237 233 472 051\">+237 233 472 051<\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Flag_of_Chad_Flat_Round-150x150.png\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Flag_of_Chad_Flat_Round-150x150.png 150w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Flag_of_Chad_Flat_Round-300x300.png 300w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Flag_of_Chad_Flat_Round-1024x1024.png 1024w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Flag_of_Chad_Flat_Round-768x768.png 768w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Flag_of_Chad_Flat_Round-1536x1536.png 1536w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Flag_of_Chad_Flat_Round-2048x2048.png 2048w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Flag_of_Chad_Flat_Round-70x70.png 70w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>                                <span class=\"card__dot\" style=\"background-color:#0e2d46;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2736\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2736\">\n                                <h3 class=\"card-title mb-0 pe-4\">Chad<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2736\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>Quartier Ndjari, carre 8<br \/>\nPorte 109 \u2013 Ndjamena<br \/>\n<br \/>\n<br \/>\nAbderahim Issa<\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+235 63 614 125\">+235 63 614 125<\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/06\/China-150x150.png\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/06\/China-150x150.png 150w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/06\/China-70x70.png 70w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/06\/China.png 250w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>                                <span class=\"card__dot\" style=\"background-color:#0e2d46;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2735\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2735\">\n                                <h3 class=\"card-title mb-0 pe-4\">China<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2735\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>Beijing <br \/>\n<br \/>\n<br \/>\n<br \/>\nMariia Androshchuk<\/p>\n                                                                            <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/Colombia-150x150.png\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/Colombia-150x150.png 150w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/Colombia-70x70.png 70w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/Colombia.png 250w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>                                <span class=\"card__dot\" style=\"background-color:#0e2d46;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2737\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2737\">\n                                <h3 class=\"card-title mb-0 pe-4\">Colombia<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2737\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>Carrera 7 # 75 66<br \/>\n110221, Bogot\u00e1<br \/>\n<br \/>\nPaola Sanchez Otero<\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+57 320 4668460\">+57 320 4668460<\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/04\/Czech-150x150.png\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/04\/Czech-150x150.png 150w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/04\/Czech-300x300.png 300w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/04\/Czech-70x70.png 70w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/04\/Czech.png 500w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>                                <span class=\"card__dot\" style=\"background-color:#5bc1f3;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2738\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2738\">\n                                <h3 class=\"card-title mb-0 pe-4\">Rep\u00fablica Checa<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2738\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>Moravskoslezsky kraj, <br \/>\nOstrava<\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+31 (0) 88 \u2013 536 00 00\">+31 (0) 88 \u2013 536 00 00<\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/denmark-flag--150x150.jpg\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" \/>                                <span class=\"card__dot\" style=\"background-color:#5bc1f3;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2740\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2740\">\n                                <h3 class=\"card-title mb-0 pe-4\">Dinamarca<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2740\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>Christian X&#8217;s Vej 22<br \/>\n6100 Haderslev<\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+31 (0) 88 \u2013 536 00 00\">+31 (0) 88 \u2013 536 00 00<\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Equatorial_Guinea_-150x150.png\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Equatorial_Guinea_-150x150.png 150w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Equatorial_Guinea_-300x300.png 300w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Equatorial_Guinea_-768x768.png 768w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Equatorial_Guinea_-70x70.png 70w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Equatorial_Guinea_.png 1024w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>                                <span class=\"card__dot\" style=\"background-color:#0e2d46;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2739\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2739\">\n                                <h3 class=\"card-title mb-0 pe-4\">Guinea Ecuatorial<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2739\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>Carretera del Aeropuerto Km 4<br \/>\nMalabo<br \/>\n<br \/>\nRoberto Akapo<\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+240 222 047 187\">+240 222 047 187<\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/flag_fr.svg\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" \/>                                <span class=\"card__dot\" style=\"background-color:#5bc1f3;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2741\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2741\">\n                                <h3 class=\"card-title mb-0 pe-4\">Francia<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2741\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>43\/47 Avenue de la Grande Arm\u00e9e<br \/>\n75116, Paris<\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+31 (0) 88 \u2013 536 00 00\">+31 (0) 88 \u2013 536 00 00<\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/flag_de.svg\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" \/>                                <span class=\"card__dot\" style=\"background-color:#FF7F00;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2744\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2744\">\n                                <h3 class=\"card-title mb-0 pe-4\">Alemania<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2744\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>Nino-Allee 11<br \/>\n48529 Nordhorn<br \/>\n<br \/>\n<br \/>\nHerbert Dirkes<\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:  +49 (0)5921 857 970\">  +49 (0)5921 857 970<\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/Ghana-150x150.png\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/Ghana-150x150.png 150w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/Ghana-70x70.png 70w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/Ghana.png 250w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>                                <span class=\"card__dot\" style=\"background-color:#0e2d46;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2743\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2743\">\n                                <h3 class=\"card-title mb-0 pe-4\">Ghana<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2743\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>Plot B17, Johnstone Street<br \/>\nCommunity 22 &#8211; Tema<br \/>\n<br \/>\n<br \/>\nFrederick Dodoo<\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+233 302 778 432\">+233 302 778 432<\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/italy-150x150.png\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/italy-150x150.png 150w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/italy-70x70.png 70w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/italy.png 250w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>                                <span class=\"card__dot\" style=\"background-color:#0e2d46;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2742\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2742\">\n                                <h3 class=\"card-title mb-0 pe-4\">Italia<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2742\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>Via Manzoni 20, <br \/>\n20900 Monza (MB), Italy<\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+31 (0) 88 536 00 33  \">+31 (0) 88 536 00 33  <\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Kazachstan-150x150.png\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Kazachstan-150x150.png 150w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Kazachstan-300x300.png 300w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Kazachstan-70x70.png 70w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Kazachstan.png 512w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>                                <span class=\"card__dot\" style=\"background-color:#FF7F00;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2746\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2746\">\n                                <h3 class=\"card-title mb-0 pe-4\">Kazajist\u00e1n<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2746\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>Tole bi street 291\/291\u0430<br \/>\n050031, Almaty<br \/>\n<br \/>\n<br \/>\nSergey Litvinenko<\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+7 495 51 40 394\">+7 495 51 40 394<\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/Luxembourg-150x150.png\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/Luxembourg-150x150.png 150w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/Luxembourg-300x300.png 300w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/Luxembourg-1024x1024.png 1024w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/Luxembourg-768x768.png 768w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/Luxembourg-1536x1536.png 1536w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/Luxembourg-2048x2048.png 2048w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/Luxembourg-70x70.png 70w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>                                <span class=\"card__dot\" style=\"background-color:#5bc1f3;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2745\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2745\">\n                                <h3 class=\"card-title mb-0 pe-4\">Luxemburgo<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2745\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>1, rue Jean Piret<br \/>\nL-2013 Luxembourg<\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+31 (0) 88 \u2013 536 00 00\">+31 (0) 88 \u2013 536 00 00<\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/netherlands-150x150.jpg\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" \/>                                <span class=\"card__dot\" style=\"background-color:#FF7F00;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2748\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2748\">\n                                <h3 class=\"card-title mb-0 pe-4\">Pa\u00edses Bajos<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2748\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>Neon 15I<br \/>\n4751 XA Oud Gastel<br \/>\n<br \/>\n<br \/>\nSaid Machmoedov<\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+31 (0) 88 \u2013 536 00 00\">+31 (0) 88 \u2013 536 00 00<\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Poland-1-150x150.jpg\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Poland-1-150x150.jpg 150w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Poland-1-300x300.jpg 300w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Poland-1-70x70.jpg 70w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Poland-1.jpg 450w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>                                <span class=\"card__dot\" style=\"background-color:#FF7F00;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2747\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2747\">\n                                <h3 class=\"card-title mb-0 pe-4\">Polonia<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2747\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>O3 Business Campus<br \/>\nUl. Opolska 110<br \/>\n31-323 Cracow <br \/>\n<br \/>\nDawid Ostrowski<\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+48 12 346 50 37  \">+48 12 346 50 37  <\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/04\/Romania-150x150.jpeg\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/04\/Romania-150x150.jpeg 150w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/04\/Romania-300x300.jpeg 300w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/04\/Romania-70x70.jpeg 70w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/04\/Romania.jpeg 450w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>                                <span class=\"card__dot\" style=\"background-color:#5bc1f3;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2701\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2701\">\n                                <h3 class=\"card-title mb-0 pe-4\">Ruman\u00eda<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2701\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>Calea Grivi\u021bei 84-98, <br \/>\n010735 Bucharest<\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+31 (0) 88 \u2013 536 00 00\">+31 (0) 88 \u2013 536 00 00<\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Saudi-150x150.png\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Saudi-150x150.png 150w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Saudi-300x300.png 300w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Saudi-70x70.png 70w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Saudi.png 500w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>                                <span class=\"card__dot\" style=\"background-color:#FF7F00;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2702\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2702\">\n                                <h3 class=\"card-title mb-0 pe-4\">Arabia Saudita<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2702\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>8263 Al Jubail Industrial City 660 St. <br \/>\nAl Shatee Complex, Office No. 5<br \/>\nSudayr Dist.<br \/>\nAl Jubail 35811-4977,<br \/>\nKingdom of Saudi Arabia<br \/>\n<br \/>\n<br \/>\nSulaiman Al-Gatai<\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+966 (0) 13 344 4599\">+966 (0) 13 344 4599<\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/South-korea-150x150.png\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/South-korea-150x150.png 150w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/South-korea-300x300.png 300w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/South-korea-70x70.png 70w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/South-korea.png 500w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>                                <span class=\"card__dot\" style=\"background-color:#0e2d46;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2703\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2703\">\n                                <h3 class=\"card-title mb-0 pe-4\">Corea del Sur<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2703\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>Machunro 21 Gil 14<br \/>\nSongpa- GU Seoul<br \/>\n<br \/>\n<br \/>\n<br \/>\n<br \/>\nWiston Francis<\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+ 8210 3747 5524\">+ 8210 3747 5524<\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/04\/Sweden-Flag-150x150.png\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/04\/Sweden-Flag-150x150.png 150w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/04\/Sweden-Flag-300x300.png 300w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/04\/Sweden-Flag-70x70.png 70w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/04\/Sweden-Flag.png 512w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>                                <span class=\"card__dot\" style=\"background-color:#5bc1f3;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2705\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2705\">\n                                <h3 class=\"card-title mb-0 pe-4\">Suecia<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2705\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+31 (0) 88 \u2013 536 00 00\">+31 (0) 88 \u2013 536 00 00<\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Swiss-150x150.jpg\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Swiss-150x150.jpg 150w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Swiss-300x300.jpg 300w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Swiss-768x768.jpg 768w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Swiss-70x70.jpg 70w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/Swiss.jpg 1024w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>                                <span class=\"card__dot\" style=\"background-color:#5bc1f3;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2704\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2704\">\n                                <h3 class=\"card-title mb-0 pe-4\">Suiza<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2704\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>Bellikerstrasse 15<br \/>\n8965 Berikon<br \/>\n<br \/>\n<br \/>\n<br \/>\nHerbert Dirkes<\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+49 (0)5921 857 970\">+49 (0)5921 857 970<\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/UAE-150x150.png\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/UAE-150x150.png 150w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/UAE-300x300.png 300w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/UAE-70x70.png 70w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/03\/UAE.png 500w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>                                <span class=\"card__dot\" style=\"background-color:#FF7F00;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2706\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2706\">\n                                <h3 class=\"card-title mb-0 pe-4\">EAU<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2706\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>Dubai South Free Zone<br \/>\nBuilding A3, 3rd. Floor Office Nr. 1 <br \/>\n<br \/>\n<br \/>\nKoos Vogel<\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+971 566 445 946\">+971 566 445 946<\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/06\/UK-150x150.png\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/06\/UK-150x150.png 150w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/06\/UK-300x300.png 300w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/06\/UK-1024x1024.png 1024w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/06\/UK-768x768.png 768w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/06\/UK-1536x1536.png 1536w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/06\/UK-70x70.png 70w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/06\/UK.png 2048w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>                                <span class=\"card__dot\" style=\"background-color:#FF7F00;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2709\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2709\">\n                                <h3 class=\"card-title mb-0 pe-4\">Reino Unido<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2709\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>The Technology Centre, Wolverhampton Science Park Ltd, Glaisher Drive, Wolverhampton WV10 9RU<br \/>\n<br \/>\nGary Phillips<\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+44 1902 287 216\">+44 1902 287 216<\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"col-12 col-lg-4 col-xl-3\">\n                        <div class=\"card card--location\">\n                            <div class=\"card-header pb-4\">\n                                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/USA-1-150x150.png\" class=\"flag img-fluid\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/USA-1-150x150.png 150w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/USA-1-300x300.png 300w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/USA-1-70x70.png 70w, https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/USA-1.png 500w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>                                <span class=\"card__dot\" style=\"background-color:#FF7F00;\"><\/span>\n                            <\/div>\n                            \n\n                    \n\n                            <a class=\"stretched-link d-flex align-items-center justify-content-between text-decoration-none collapsed\" data-bs-toggle=\"collapse\" href=\"#collapseExample_2708\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample_2708\">\n                                <h3 class=\"card-title mb-0 pe-4\">Estados Unidos<\/h3>\n                                <svg class=\"icon icon--12\">\n                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#chevron-down\"><\/use>\n                                <\/svg>\n                            <\/a>\n\n                            <div class=\"collapse\" id=\"collapseExample_2708\">\n                                <div class=\"h-100 d-flex flex-column pt-4\">\n                                    <div class=\"card-body\">\n                                                                                    <p>4579 South Wayside<br \/>\nHouston, TX 77087<\/p>\n                                                                            <\/div>\n                                                                            <div class=\"card-footer mt-4\">\n                                            <p class=\"card-subtitle\">\n                                                <svg class=\"icon icon--16 icon--lg-18 me-2\">\n                                                    <use xlink:href=\"https:\/\/www.corlidogroup.com\/wp-content\/themes\/corlido\/build\/img\/symbols.svg#mobile\"><\/use>\n                                                <\/svg>\n                                                <a href=\"tel:+1(713)382-0121\">+1(713)382-0121<\/a>\n                                            <\/p>\n                                        <\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                            <\/div>\n    <\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-2751","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ubicaciones - Corlido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.corlidogroup.com\/es\/ubicaciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ubicaciones - Corlido\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.corlidogroup.com\/es\/ubicaciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Corlido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CorlidoGroup\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-02T15:43:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.corlidogroup.com\\\/es\\\/ubicaciones\\\/\",\"url\":\"https:\\\/\\\/www.corlidogroup.com\\\/es\\\/ubicaciones\\\/\",\"name\":\"Ubicaciones - Corlido\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.corlidogroup.com\\\/es\\\/#website\"},\"datePublished\":\"2024-02-13T14:27:59+00:00\",\"dateModified\":\"2026-02-02T15:43:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.corlidogroup.com\\\/es\\\/ubicaciones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.corlidogroup.com\\\/es\\\/ubicaciones\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.corlidogroup.com\\\/es\\\/ubicaciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.corlidogroup.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ubicaciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.corlidogroup.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.corlidogroup.com\\\/es\\\/\",\"name\":\"Corlido Group\",\"description\":\"We optimise your procurement process\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.corlidogroup.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.corlidogroup.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.corlidogroup.com\\\/es\\\/#organization\",\"name\":\"Corlido Group\",\"url\":\"https:\\\/\\\/www.corlidogroup.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.corlidogroup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.corlidogroup.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Corlido-favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.corlidogroup.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Corlido-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Corlido Group\"},\"image\":{\"@id\":\"https:\\\/\\\/www.corlidogroup.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CorlidoGroup\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/1372474\\\/\",\"https:\\\/\\\/www.instagram.com\\\/corlidogroup\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ubicaciones - Corlido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.corlidogroup.com\/es\/ubicaciones\/","og_locale":"es_ES","og_type":"article","og_title":"Ubicaciones - Corlido","og_url":"https:\/\/www.corlidogroup.com\/es\/ubicaciones\/","og_site_name":"Corlido","article_publisher":"https:\/\/www.facebook.com\/CorlidoGroup\/","article_modified_time":"2026-02-02T15:43:08+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.corlidogroup.com\/es\/ubicaciones\/","url":"https:\/\/www.corlidogroup.com\/es\/ubicaciones\/","name":"Ubicaciones - Corlido","isPartOf":{"@id":"https:\/\/www.corlidogroup.com\/es\/#website"},"datePublished":"2024-02-13T14:27:59+00:00","dateModified":"2026-02-02T15:43:08+00:00","breadcrumb":{"@id":"https:\/\/www.corlidogroup.com\/es\/ubicaciones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.corlidogroup.com\/es\/ubicaciones\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.corlidogroup.com\/es\/ubicaciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.corlidogroup.com\/es\/"},{"@type":"ListItem","position":2,"name":"Ubicaciones"}]},{"@type":"WebSite","@id":"https:\/\/www.corlidogroup.com\/es\/#website","url":"https:\/\/www.corlidogroup.com\/es\/","name":"Corlido Group","description":"We optimise your procurement process","publisher":{"@id":"https:\/\/www.corlidogroup.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.corlidogroup.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.corlidogroup.com\/es\/#organization","name":"Corlido Group","url":"https:\/\/www.corlidogroup.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.corlidogroup.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/cropped-Corlido-favicon.png","contentUrl":"https:\/\/www.corlidogroup.com\/wp-content\/uploads\/2024\/02\/cropped-Corlido-favicon.png","width":512,"height":512,"caption":"Corlido Group"},"image":{"@id":"https:\/\/www.corlidogroup.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CorlidoGroup\/","https:\/\/www.linkedin.com\/company\/1372474\/","https:\/\/www.instagram.com\/corlidogroup\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.corlidogroup.com\/es\/wp-json\/wp\/v2\/pages\/2751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.corlidogroup.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.corlidogroup.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.corlidogroup.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.corlidogroup.com\/es\/wp-json\/wp\/v2\/comments?post=2751"}],"version-history":[{"count":1,"href":"https:\/\/www.corlidogroup.com\/es\/wp-json\/wp\/v2\/pages\/2751\/revisions"}],"predecessor-version":[{"id":2753,"href":"https:\/\/www.corlidogroup.com\/es\/wp-json\/wp\/v2\/pages\/2751\/revisions\/2753"}],"wp:attachment":[{"href":"https:\/\/www.corlidogroup.com\/es\/wp-json\/wp\/v2\/media?parent=2751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}